{"id":760,"date":"2017-04-30T13:25:07","date_gmt":"2017-04-30T12:25:07","guid":{"rendered":"http:\/\/afan.fr\/blog\/?p=760"},"modified":"2017-04-30T13:25:07","modified_gmt":"2017-04-30T12:25:07","slug":"nme-pour-trains-160-tremie-evs","status":"publish","type":"post","link":"https:\/\/afan.fr\/blog\/index.php\/2017\/04\/30\/nme-pour-trains-160-tremie-evs\/","title":{"rendered":"NME pour Trains 160 &#8211; Tr\u00e9mie EVS"},"content":{"rendered":"<p><span style=\"color: #000080;\">NME a r\u00e9alis\u00e9 une reproduction du wagon moderne \u00e0 pulv\u00e9rulents de 80 m3, type Uacns.<br \/>\n<\/span><span style=\"color: #000080;\">Trains 160 propose en exclusivit\u00e9 2 versions des wagons immatricul\u00e9s en France par la St\u00e9 EVS et avec bogies conformes\u00a0:<\/span><\/p>\n<p><span style=\"color: #000080;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-761 size-full\" src=\"https:\/\/afan.fr\/blog\/wp-content\/uploads\/2017\/04\/2017-04_evs1_nmetrains160.jpg\" alt=\"\" width=\"900\" height=\"295\" srcset=\"https:\/\/afan.fr\/blog\/wp-content\/uploads\/2017\/04\/2017-04_evs1_nmetrains160.jpg 900w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2017\/04\/2017-04_evs1_nmetrains160-300x98.jpg 300w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2017\/04\/2017-04_evs1_nmetrains160-768x252.jpg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/>&#8211; Livr\u00e9e de l&#8217;\u00e9poque VI avec nouveau sigle, R\u00e9f. 203614<\/span><\/p>\n<p><span style=\"color: #000080;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-762 size-full\" src=\"https:\/\/afan.fr\/blog\/wp-content\/uploads\/2017\/04\/2017-04_evs2_nmetrains160.jpg\" alt=\"\" width=\"900\" height=\"274\" srcset=\"https:\/\/afan.fr\/blog\/wp-content\/uploads\/2017\/04\/2017-04_evs2_nmetrains160.jpg 900w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2017\/04\/2017-04_evs2_nmetrains160-300x91.jpg 300w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2017\/04\/2017-04_evs2_nmetrains160-768x234.jpg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/>&#8211; Livr\u00e9e de l&#8217;\u00e9poque V\/VI avec sigle ancien, R\u00e9f. 2036632.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>NME a r\u00e9alis\u00e9 une reproduction du wagon moderne \u00e0 pulv\u00e9rulents de 80 m3, type Uacns. Trains 160 propose en exclusivit\u00e9 2 versions des wagons immatricul\u00e9s en France par la St\u00e9 EVS et avec bogies conformes\u00a0: &#8211; Livr\u00e9e de l&#8217;\u00e9poque VI avec nouveau sigle, R\u00e9f. 203614 &#8211; Livr\u00e9e de l&#8217;\u00e9poque V\/VI avec sigle ancien, R\u00e9f. 2036632.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_s2mail":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-760","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts\/760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=760"}],"version-history":[{"count":1,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts\/760\/revisions"}],"predecessor-version":[{"id":763,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts\/760\/revisions\/763"}],"wp:attachment":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}