{"id":5650,"date":"2026-04-13T14:47:08","date_gmt":"2026-04-13T13:47:08","guid":{"rendered":"https:\/\/afan.fr\/blog\/?p=5650"},"modified":"2026-04-18T14:46:37","modified_gmt":"2026-04-18T13:46:37","slug":"afan-magazn-n-188-2","status":"publish","type":"post","link":"https:\/\/afan.fr\/blog\/index.php\/2026\/04\/13\/afan-magazn-n-188-2\/","title":{"rendered":"AFAN &#8211; MAGAZ&#8217;N N\u00b0 188"},"content":{"rendered":"\n<p>Comme planifi\u00e9, MAGAZ&#8217;N N\u00b0 188, bulletin de liaison r\u00e9serv\u00e9 aux adh\u00e9rents de l&#8217;AFAN, a \u00e9t\u00e9 distribu\u00e9.<br>Il s&#8217;agit du dernier Bulletin de l&#8217;exercice 2025.<\/p>\n\n\n\n<p class=\"has-vivid-red-color has-text-color has-link-color wp-elements-56fa88e7267e9161d9a610bdc3d66183\"><strong>INFORMATION IMPORTANTE<\/strong><br>Sur l&#8217;\u00e9tiquette adresse il est mentionn\u00e9 2026 si nous avons re\u00e7u votre renouvellement. Probl\u00e8me, suite \u00e0 un dysfonctionnement du centre de tri, nous n&#8217;avons pas re\u00e7u de courrier entre, en gros, le 10 mars et le 10 avril et cela malgr\u00e9 nos interrogations pressantes. Donc, si vous avez r\u00e9gl\u00e9 par ch\u00e8que dans cette p\u00e9riode, nous n&#8217;avons pas pu les endosser. Ce sera fait cette semaine. Nous vous demandons de nous excuser pour ce contretemps bien ind\u00e9pendant de notre volont\u00e9.<\/p>\n\n\n\n<p>Le num\u00e9ro 189 est planifi\u00e9 pour une livraison mi juin. Il s&#8217;agira du premier Bulletin de l&#8217;exercice 2026, il sera exp\u00e9di\u00e9 aux adh\u00e9rents \u00e0 jour de leur cotisation 2026, la carte d&#8217;adh\u00e9rent y sera jointe.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comme planifi\u00e9, MAGAZ&#8217;N N\u00b0 188, bulletin de liaison r\u00e9serv\u00e9 aux adh\u00e9rents de l&#8217;AFAN, a \u00e9t\u00e9 distribu\u00e9.Il s&#8217;agit du dernier Bulletin de l&#8217;exercice 2025. INFORMATION IMPORTANTESur l&#8217;\u00e9tiquette adresse il est mentionn\u00e9 2026 si nous avons re\u00e7u votre renouvellement. Probl\u00e8me, suite \u00e0 un dysfonctionnement du centre de tri, nous n&#8217;avons pas re\u00e7u de courrier entre, en gros, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_s2mail":"yes","footnotes":""},"categories":[1],"tags":[],"class_list":["post-5650","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts\/5650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=5650"}],"version-history":[{"count":4,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts\/5650\/revisions"}],"predecessor-version":[{"id":5664,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts\/5650\/revisions\/5664"}],"wp:attachment":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=5650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=5650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=5650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}