{"id":5138,"date":"2025-03-08T07:16:08","date_gmt":"2025-03-08T06:16:08","guid":{"rendered":"http:\/\/afan.fr\/blog\/?p=5138"},"modified":"2025-03-08T07:16:08","modified_gmt":"2025-03-08T06:16:08","slug":"minitrix-coffret-de-2-wagons-plats","status":"publish","type":"post","link":"https:\/\/afan.fr\/blog\/index.php\/2025\/03\/08\/minitrix-coffret-de-2-wagons-plats\/","title":{"rendered":"Minitrix &#8211; Coffret de 2 wagons plats"},"content":{"rendered":"\n<p>Minitrix vient de commercialiser son coffret  de 2 plats \u00e0 bogies, bords bas et ranchers Uas, charg\u00e9s de rails, \u00e9poque VI ; R\u00e9f.18290. A noter les diff\u00e9rences entre les deux wagons&#8230; bonne id\u00e9e !<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"253\" src=\"https:\/\/afan.fr\/blog\/wp-content\/uploads\/2025\/03\/2025-03_plat1_trix-1024x253.jpg\" alt=\"\" class=\"wp-image-5139\" srcset=\"https:\/\/afan.fr\/blog\/wp-content\/uploads\/2025\/03\/2025-03_plat1_trix-1024x253.jpg 1024w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2025\/03\/2025-03_plat1_trix-300x74.jpg 300w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2025\/03\/2025-03_plat1_trix-768x190.jpg 768w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2025\/03\/2025-03_plat1_trix.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"240\" src=\"https:\/\/afan.fr\/blog\/wp-content\/uploads\/2025\/03\/2025-03_plat2_trix-1024x240.jpg\" alt=\"\" class=\"wp-image-5140\" srcset=\"https:\/\/afan.fr\/blog\/wp-content\/uploads\/2025\/03\/2025-03_plat2_trix-1024x240.jpg 1024w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2025\/03\/2025-03_plat2_trix-300x70.jpg 300w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2025\/03\/2025-03_plat2_trix-768x180.jpg 768w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2025\/03\/2025-03_plat2_trix.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Minitrix vient de commercialiser son coffret de 2 plats \u00e0 bogies, bords bas et ranchers Uas, charg\u00e9s de rails, \u00e9poque VI ; R\u00e9f.18290. A noter les diff\u00e9rences entre les deux wagons&#8230; bonne id\u00e9e !<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_s2mail":"yes","footnotes":""},"categories":[1],"tags":[],"class_list":["post-5138","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts\/5138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=5138"}],"version-history":[{"count":1,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts\/5138\/revisions"}],"predecessor-version":[{"id":5141,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts\/5138\/revisions\/5141"}],"wp:attachment":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=5138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=5138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=5138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}