{"id":4982,"date":"2024-10-18T13:37:09","date_gmt":"2024-10-18T12:37:09","guid":{"rendered":"http:\/\/afan.fr\/blog\/?p=4982"},"modified":"2024-10-18T13:37:09","modified_gmt":"2024-10-18T12:37:09","slug":"loco-revue-projets-de-reseaux","status":"publish","type":"post","link":"https:\/\/afan.fr\/blog\/index.php\/2024\/10\/18\/loco-revue-projets-de-reseaux\/","title":{"rendered":"Loco Revue &#8211; Projets de r\u00e9seaux"},"content":{"rendered":"\n<p>Loco Revue renouvelle le concept des ouvrages de plans de r\u00e9seaux en compl\u00e9tant le plan proprement dit par une documentation de la r\u00e9alit\u00e9, des informations sur la r\u00e9alisation, dont en particulier la r\u00e9alisation du c\u00e2blage, et des photos du r\u00e9sultat possible. 11 propositions sont ainsi pr\u00e9sent\u00e9es dans le Dossier Thematique N\u00b0 5, dont 4 \u00e0 l&#8217;\u00e9chelle N. Une v\u00e9ritable mine d&#8217;id\u00e9es pour qui veut se lancer dans la construction d&#8217;un r\u00e9seau.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"537\" height=\"730\" src=\"https:\/\/afan.fr\/blog\/wp-content\/uploads\/2024\/10\/DT05-Couvb.jpg\" alt=\"\" class=\"wp-image-4984\" srcset=\"https:\/\/afan.fr\/blog\/wp-content\/uploads\/2024\/10\/DT05-Couvb.jpg 537w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2024\/10\/DT05-Couvb-221x300.jpg 221w\" sizes=\"auto, (max-width: 537px) 100vw, 537px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Loco Revue renouvelle le concept des ouvrages de plans de r\u00e9seaux en compl\u00e9tant le plan proprement dit par une documentation de la r\u00e9alit\u00e9, des informations sur la r\u00e9alisation, dont en particulier la r\u00e9alisation du c\u00e2blage, et des photos du r\u00e9sultat possible. 11 propositions sont ainsi pr\u00e9sent\u00e9es dans le Dossier Thematique N\u00b0 5, dont 4 \u00e0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_s2mail":"yes","footnotes":""},"categories":[1],"tags":[],"class_list":["post-4982","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts\/4982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=4982"}],"version-history":[{"count":2,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts\/4982\/revisions"}],"predecessor-version":[{"id":4985,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts\/4982\/revisions\/4985"}],"wp:attachment":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=4982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=4982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=4982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}