{"id":4874,"date":"2024-07-25T12:40:16","date_gmt":"2024-07-25T11:40:16","guid":{"rendered":"http:\/\/afan.fr\/blog\/?p=4874"},"modified":"2024-07-25T12:40:16","modified_gmt":"2024-07-25T11:40:16","slug":"minitrix-des-citernes","status":"publish","type":"post","link":"https:\/\/afan.fr\/blog\/index.php\/2024\/07\/25\/minitrix-des-citernes\/","title":{"rendered":"Minitrix &#8211; Des citernes"},"content":{"rendered":"\n<p>Minitrix vient de commercialiser deux nouveaut\u00e9s concernant des citernes :<br>Citerne \u00e0 2 essieux &#8220;Millet&#8221; immatricul\u00e9e \u00e0 la SNCF (gamme \u00e9conomique), Ep V, R\u00e9f. 18098<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"498\" src=\"https:\/\/afan.fr\/blog\/wp-content\/uploads\/2024\/07\/2024-07_millet_2ess_trix.jpg\" alt=\"\" class=\"wp-image-4876\" srcset=\"https:\/\/afan.fr\/blog\/wp-content\/uploads\/2024\/07\/2024-07_millet_2ess_trix.jpg 900w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2024\/07\/2024-07_millet_2ess_trix-300x166.jpg 300w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2024\/07\/2024-07_millet_2ess_trix-768x425.jpg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<p>Coffret de 3 citernes \u00e0 bogies &#8220;Millet&#8221; type Zagns pour produits chimiques, immatricul\u00e9es aux NS mais susceptibles de circuler en France, Ep VI, R\u00e9f 18268.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"381\" src=\"https:\/\/afan.fr\/blog\/wp-content\/uploads\/2024\/07\/2024-07_millet_bogie_trix.jpg\" alt=\"\" class=\"wp-image-4875\" srcset=\"https:\/\/afan.fr\/blog\/wp-content\/uploads\/2024\/07\/2024-07_millet_bogie_trix.jpg 1000w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2024\/07\/2024-07_millet_bogie_trix-300x114.jpg 300w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2024\/07\/2024-07_millet_bogie_trix-768x293.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Minitrix vient de commercialiser deux nouveaut\u00e9s concernant des citernes :Citerne \u00e0 2 essieux &#8220;Millet&#8221; immatricul\u00e9e \u00e0 la SNCF (gamme \u00e9conomique), Ep V, R\u00e9f. 18098 Coffret de 3 citernes \u00e0 bogies &#8220;Millet&#8221; type Zagns pour produits chimiques, immatricul\u00e9es aux NS mais susceptibles de circuler en France, Ep VI, R\u00e9f 18268.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_s2mail":"yes","footnotes":""},"categories":[1],"tags":[],"class_list":["post-4874","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts\/4874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=4874"}],"version-history":[{"count":2,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts\/4874\/revisions"}],"predecessor-version":[{"id":4878,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts\/4874\/revisions\/4878"}],"wp:attachment":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=4874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=4874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=4874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}