{"id":4677,"date":"2024-03-06T10:05:20","date_gmt":"2024-03-06T09:05:20","guid":{"rendered":"http:\/\/afan.fr\/blog\/?p=4677"},"modified":"2024-03-06T10:05:57","modified_gmt":"2024-03-06T09:05:57","slug":"tj-modeles-batiments-modellbau-laffont","status":"publish","type":"post","link":"https:\/\/afan.fr\/blog\/index.php\/2024\/03\/06\/tj-modeles-batiments-modellbau-laffont\/","title":{"rendered":"TJ-Mod\u00e8les &#8211; B\u00e2timents Modellbau-Laffont"},"content":{"rendered":"\n<p>TJ-Mod\u00e8les annonce la commercialisation par sa boutique en ligne de 2 kits de b\u00e2timents fran\u00e7ais r\u00e9alis\u00e9s par le fabricant allemand Modellbau Laffont (carton d&#8217;architecture d\u00e9coup\u00e9 au laser). <br><strong>N8101 : Mairie de Wissant<\/strong> &#8211; Bien que ce soit une commune du Pas-de-Calais, sur la c\u00f4te d\u2019Opale, cette mairie au style original pourra ais\u00e9ment \u00eatre implant\u00e9e au c\u0153ur des villages de tous les r\u00e9seaux. Dimensions : 83x54x61mm.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"761\" src=\"https:\/\/afan.fr\/blog\/wp-content\/uploads\/2024\/03\/N8101-TJ-Modeles-1024x761-1024x761.jpg\" alt=\"\" class=\"wp-image-4678\" srcset=\"https:\/\/afan.fr\/blog\/wp-content\/uploads\/2024\/03\/N8101-TJ-Modeles-1024x761.jpg 1024w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2024\/03\/N8101-TJ-Modeles-1024x761-300x223.jpg 300w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2024\/03\/N8101-TJ-Modeles-1024x761-768x571.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><strong>N9601 : Set de Maisons de Village fran\u00e7ais compos\u00e9 :<\/strong><br>&#8211; D\u2019une maison individuelle \u00e0 1 \u00e9tage (dimensions 41x34x54mm) avec des fen\u00eatres dans un style \u00ab industriel \u00bb. Possibilit\u00e9 de la raccourcir pour l\u2019accoler \u00e0 un autre b\u00e2timent.<br>&#8211; D\u2019une annexe (dimensions 21x17x18mm) pouvant \u00eatre accol\u00e9e au b\u00e2timent de votre choix<br>&#8211; D\u2019une petite maison \u00e0 ossature bois (dimensions 53x31x36mm)<br>&#8211; D\u2019un atelier (dimensions 93x35x44mm)<br>&#8211; D\u2019un abribus bois (dimensions 17x17x19mm).<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"376\" src=\"https:\/\/afan.fr\/blog\/wp-content\/uploads\/2024\/03\/N9601-TJ-Modeles-1024x376-1024x376.jpg\" alt=\"\" class=\"wp-image-4679\" srcset=\"https:\/\/afan.fr\/blog\/wp-content\/uploads\/2024\/03\/N9601-TJ-Modeles-1024x376.jpg 1024w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2024\/03\/N9601-TJ-Modeles-1024x376-300x110.jpg 300w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2024\/03\/N9601-TJ-Modeles-1024x376-768x282.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>D&#8217;autres kits compl\u00e9mentaires sont en cours d&#8217;\u00e9tude.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TJ-Mod\u00e8les annonce la commercialisation par sa boutique en ligne de 2 kits de b\u00e2timents fran\u00e7ais r\u00e9alis\u00e9s par le fabricant allemand Modellbau Laffont (carton d&#8217;architecture d\u00e9coup\u00e9 au laser). N8101 : Mairie de Wissant &#8211; Bien que ce soit une commune du Pas-de-Calais, sur la c\u00f4te d\u2019Opale, cette mairie au style original pourra ais\u00e9ment \u00eatre implant\u00e9e au [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_s2mail":"yes","footnotes":""},"categories":[1],"tags":[],"class_list":["post-4677","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts\/4677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=4677"}],"version-history":[{"count":1,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts\/4677\/revisions"}],"predecessor-version":[{"id":4680,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts\/4677\/revisions\/4680"}],"wp:attachment":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=4677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=4677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=4677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}