{"id":4475,"date":"2023-11-16T10:41:56","date_gmt":"2023-11-16T09:41:56","guid":{"rendered":"http:\/\/afan.fr\/blog\/?p=4475"},"modified":"2023-11-16T10:41:56","modified_gmt":"2023-11-16T09:41:56","slug":"hfr160-platine-analogique-et-tampons","status":"publish","type":"post","link":"https:\/\/afan.fr\/blog\/index.php\/2023\/11\/16\/hfr160-platine-analogique-et-tampons\/","title":{"rendered":"HFR160 &#8211; Platine analogique et tampons"},"content":{"rendered":"\n<p>HFR160 propose une platine analogique pour \u00e9quiper son Y 8000 et lui permettre d&#8217;utiliser des prestations proches de celles du mod\u00e8le DCC.<br>Il s&#8217;git d&#8217;une platine analogique avec feux leds blanc\/rouge et volant d\u2019inertie \u00e9lectronique :<br>&#8211; feux blancs allum\u00e9s machine \u00e0 l\u2019arr\u00eat<br> &#8211; anti-clignotement des feux et luminosit\u00e9 constante<br> &#8211; feux blancs allum\u00e9s \u00e0 l\u2019avant et \u00e0 l\u2019arri\u00e8re si inversion de sens fr\u00e9quent: machine en manoeuvre<br> &#8211; feux blancs allum\u00e9s \u00e0 l\u2019avant et \u00e9teins \u00e0 l\u2019arri\u00e8re \u00e0 vitesse mod\u00e9r\u00e9e: machine tractant des wagons<br> &#8211; feux blancs allum\u00e9s \u00e0 l\u2019avant et rouges \u00e0 l\u2019arri\u00e8re \u00e0 vitesse soutenue: machine seule \u201cHaut-Le-Pied\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/afan.fr\/blog\/wp-content\/uploads\/2023\/11\/HFR-704_recto_low.jpg\" alt=\"\" class=\"wp-image-4476\" srcset=\"https:\/\/afan.fr\/blog\/wp-content\/uploads\/2023\/11\/HFR-704_recto_low.jpg 800w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2023\/11\/HFR-704_recto_low-300x225.jpg 300w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2023\/11\/HFR-704_recto_low-768x576.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>Pour vos constructions personnelles ou pour am\u00e9liorer des mod\u00e8les du commerce, HFR160 propose des ensembles de tampons (impression 3D, brute ou peinte sur commande). Sont d\u00e9j\u00e0 disponibles les variantes suivantes :<br>&#8211; OCEM \u00e0 plateau rond des locotracteurs diesel Y6400, Y7100, Y51100 et vapeur 030TU<br> &#8211; U5 \u00e0 plateau carr\u00e9 des locotracteurs diesel Y6400, Y7100, Y8000<br> &#8211; U6 \u00e0 plateau rectangulaire et bords arrondis des locomotives diesel modernes: BB63500, CC65000, CC65500, BB67000, A1A68000\u2026<br>&#8211;  U6 \u00e0 plateau rectangulaire et pans coup\u00e9 des locomotives diesel anciennes: 060DB \/ CC65000\u2026<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/afan.fr\/blog\/wp-content\/uploads\/2023\/11\/HFR-087.u5_844_low.jpg\" alt=\"\" class=\"wp-image-4477\" srcset=\"https:\/\/afan.fr\/blog\/wp-content\/uploads\/2023\/11\/HFR-087.u5_844_low.jpg 800w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2023\/11\/HFR-087.u5_844_low-300x225.jpg 300w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2023\/11\/HFR-087.u5_844_low-768x576.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>HFR160 propose une platine analogique pour \u00e9quiper son Y 8000 et lui permettre d&#8217;utiliser des prestations proches de celles du mod\u00e8le DCC.Il s&#8217;git d&#8217;une platine analogique avec feux leds blanc\/rouge et volant d\u2019inertie \u00e9lectronique :&#8211; feux blancs allum\u00e9s machine \u00e0 l\u2019arr\u00eat &#8211; anti-clignotement des feux et luminosit\u00e9 constante &#8211; feux blancs allum\u00e9s \u00e0 l\u2019avant et [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_s2mail":"yes","footnotes":""},"categories":[1],"tags":[],"class_list":["post-4475","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts\/4475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=4475"}],"version-history":[{"count":1,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts\/4475\/revisions"}],"predecessor-version":[{"id":4478,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts\/4475\/revisions\/4478"}],"wp:attachment":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=4475"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=4475"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=4475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}