{"id":3733,"date":"2022-06-13T14:22:11","date_gmt":"2022-06-13T13:22:11","guid":{"rendered":"http:\/\/afan.fr\/blog\/?p=3733"},"modified":"2022-06-15T07:49:20","modified_gmt":"2022-06-15T06:49:20","slug":"hfr160-des-plaques-en-relief","status":"publish","type":"post","link":"https:\/\/afan.fr\/blog\/index.php\/2022\/06\/13\/hfr160-des-plaques-en-relief\/","title":{"rendered":"HFR160 &#8211; Des plaques en relief"},"content":{"rendered":"\n<p>HFR160 continue de proposer de nouvelles plaques en relief permettant le marquage de mat\u00e9riel, soit en kit, soit pour remplacer des marquages peints et ceci pour des locomotives \u00e0 vapeur, diesel et \u00e9lectriques. On remarque particuli\u00e8rement des plaques pour les futures 141 R Arnold ou pour la BB 7301 Fleischmann par exemple.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"410\" height=\"320\" src=\"https:\/\/afan.fr\/blog\/wp-content\/uploads\/2022\/06\/HFR-080.141R1173_tiny-1.jpg\" alt=\"\" class=\"wp-image-3734\" srcset=\"https:\/\/afan.fr\/blog\/wp-content\/uploads\/2022\/06\/HFR-080.141R1173_tiny-1.jpg 410w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2022\/06\/HFR-080.141R1173_tiny-1-300x234.jpg 300w\" sizes=\"auto, (max-width: 410px) 100vw, 410px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"280\" src=\"https:\/\/afan.fr\/blog\/wp-content\/uploads\/2022\/06\/HFR-080.BB17064_tiny-1.jpg\" alt=\"\" class=\"wp-image-3735\" srcset=\"https:\/\/afan.fr\/blog\/wp-content\/uploads\/2022\/06\/HFR-080.BB17064_tiny-1.jpg 640w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2022\/06\/HFR-080.BB17064_tiny-1-300x131.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption>Doc HFR160<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"273\" src=\"https:\/\/afan.fr\/blog\/wp-content\/uploads\/2022\/06\/HFR-080.BB7301_tiny.jpg\" alt=\"\" class=\"wp-image-3744\" srcset=\"https:\/\/afan.fr\/blog\/wp-content\/uploads\/2022\/06\/HFR-080.BB7301_tiny.jpg 640w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2022\/06\/HFR-080.BB7301_tiny-300x128.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"545\" src=\"https:\/\/afan.fr\/blog\/wp-content\/uploads\/2022\/06\/HFR-080.BB7301_dersou_mid-1024x545.jpg\" alt=\"\" class=\"wp-image-3745\" srcset=\"https:\/\/afan.fr\/blog\/wp-content\/uploads\/2022\/06\/HFR-080.BB7301_dersou_mid.jpg 1024w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2022\/06\/HFR-080.BB7301_dersou_mid-300x160.jpg 300w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2022\/06\/HFR-080.BB7301_dersou_mid-768x409.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>BB 7301 Fleischmann &#8211; Doc HFR160\/Dersou<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>HFR160 continue de proposer de nouvelles plaques en relief permettant le marquage de mat\u00e9riel, soit en kit, soit pour remplacer des marquages peints et ceci pour des locomotives \u00e0 vapeur, diesel et \u00e9lectriques. On remarque particuli\u00e8rement des plaques pour les futures 141 R Arnold ou pour la BB 7301 Fleischmann par exemple.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_s2mail":"yes","footnotes":""},"categories":[1],"tags":[],"class_list":["post-3733","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts\/3733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=3733"}],"version-history":[{"count":2,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts\/3733\/revisions"}],"predecessor-version":[{"id":3747,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts\/3733\/revisions\/3747"}],"wp:attachment":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=3733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=3733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=3733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}