{"id":3476,"date":"2021-12-09T08:09:54","date_gmt":"2021-12-09T07:09:54","guid":{"rendered":"http:\/\/afan.fr\/blog\/?p=3476"},"modified":"2021-12-09T08:09:54","modified_gmt":"2021-12-09T07:09:54","slug":"nlook-le-retour","status":"publish","type":"post","link":"https:\/\/afan.fr\/blog\/index.php\/2021\/12\/09\/nlook-le-retour\/","title":{"rendered":"NLOOK, le retour&#8230;"},"content":{"rendered":"\n<p>Apr\u00e8s une p\u00e9riode de rel\u00e2che, NLook revient en annon\u00e7ant, outre la disponibilit\u00e9 de ses anciennes productions, 3 nouvelles r\u00e9f\u00e9rences produites en utilisant la technique d&#8217;impression 3D ; il s&#8217;agit de :<br>&#8211; Deux poteaux t\u00e9l\u00e9phoniques routiers (R\u00e9f. PTR04) ; ces poteaux sont aussi propos\u00e9s peints, uniquement sur commande.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"438\" height=\"1024\" src=\"https:\/\/afan.fr\/blog\/wp-content\/uploads\/2021\/12\/poteau-telephonique-1-438x1024.jpg\" alt=\"\" class=\"wp-image-3477\" srcset=\"https:\/\/afan.fr\/blog\/wp-content\/uploads\/2021\/12\/poteau-telephonique-1-438x1024.jpg 438w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2021\/12\/poteau-telephonique-1-128x300.jpg 128w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2021\/12\/poteau-telephonique-1-768x1796.jpg 768w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2021\/12\/poteau-telephonique-1.jpg 1026w\" sizes=\"auto, (max-width: 438px) 100vw, 438px\" \/><\/figure>\n\n\n\n<p>&#8211; Une devanture de boutique (R\u00e9f. DB03) avec deux enseignes (cordonnier et bijoutier).<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/afan.fr\/blog\/wp-content\/uploads\/2021\/12\/20210921_164308-2-1024x1024.jpg\" alt=\"\" class=\"wp-image-3478\" srcset=\"https:\/\/afan.fr\/blog\/wp-content\/uploads\/2021\/12\/20210921_164308-2-1024x1024.jpg 1024w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2021\/12\/20210921_164308-2-150x150.jpg 150w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2021\/12\/20210921_164308-2-300x300.jpg 300w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2021\/12\/20210921_164308-2-768x768.jpg 768w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2021\/12\/20210921_164308-2.jpg 1770w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>&#8211; Une charrette de charron (R\u00e9f. LOC-01).<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/afan.fr\/blog\/wp-content\/uploads\/2021\/12\/charette--1024x1024.jpg\" alt=\"\" class=\"wp-image-3479\" srcset=\"https:\/\/afan.fr\/blog\/wp-content\/uploads\/2021\/12\/charette--1024x1024.jpg 1024w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2021\/12\/charette--150x150.jpg 150w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2021\/12\/charette--300x300.jpg 300w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2021\/12\/charette--768x768.jpg 768w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2021\/12\/charette-.jpg 1777w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Documents NLook<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s une p\u00e9riode de rel\u00e2che, NLook revient en annon\u00e7ant, outre la disponibilit\u00e9 de ses anciennes productions, 3 nouvelles r\u00e9f\u00e9rences produites en utilisant la technique d&#8217;impression 3D ; il s&#8217;agit de :&#8211; Deux poteaux t\u00e9l\u00e9phoniques routiers (R\u00e9f. PTR04) ; ces poteaux sont aussi propos\u00e9s peints, uniquement sur commande. &#8211; Une devanture de boutique (R\u00e9f. DB03) avec [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_s2mail":"yes","footnotes":""},"categories":[1],"tags":[],"class_list":["post-3476","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts\/3476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=3476"}],"version-history":[{"count":2,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts\/3476\/revisions"}],"predecessor-version":[{"id":3481,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts\/3476\/revisions\/3481"}],"wp:attachment":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=3476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=3476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=3476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}