{"id":2328,"date":"2019-11-09T14:07:16","date_gmt":"2019-11-09T13:07:16","guid":{"rendered":"http:\/\/afan.fr\/blog\/?p=2328"},"modified":"2019-11-09T14:07:21","modified_gmt":"2019-11-09T13:07:21","slug":"piko-couchettes-lunea","status":"publish","type":"post","link":"https:\/\/afan.fr\/blog\/index.php\/2019\/11\/09\/piko-couchettes-lunea\/","title":{"rendered":"Piko &#8211; Couchettes &#8220;Lun\u00e9a&#8221;"},"content":{"rendered":"\n<p>Piko vient de commercialiser son coffret de 2 voitures couchettes de type VU en d\u00e9coration &#8220;Lun\u00e9a&#8221;, une voiture de 1\u00e8re et une de 2\u00e8me. R\u00e9f. 94339<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"399\" src=\"https:\/\/afan.fr\/blog\/wp-content\/uploads\/2019\/11\/2019-11_vu_lunea_piko-1024x399.jpg\" alt=\"\" class=\"wp-image-2329\" srcset=\"https:\/\/afan.fr\/blog\/wp-content\/uploads\/2019\/11\/2019-11_vu_lunea_piko-1024x399.jpg 1024w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2019\/11\/2019-11_vu_lunea_piko-300x117.jpg 300w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2019\/11\/2019-11_vu_lunea_piko-768x300.jpg 768w, https:\/\/afan.fr\/blog\/wp-content\/uploads\/2019\/11\/2019-11_vu_lunea_piko.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Piko vient de commercialiser son coffret de 2 voitures couchettes de type VU en d\u00e9coration &#8220;Lun\u00e9a&#8221;, une voiture de 1\u00e8re et une de 2\u00e8me. R\u00e9f. 94339<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_s2mail":"yes","footnotes":""},"categories":[1],"tags":[],"class_list":["post-2328","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts\/2328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=2328"}],"version-history":[{"count":1,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts\/2328\/revisions"}],"predecessor-version":[{"id":2330,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/posts\/2328\/revisions\/2330"}],"wp:attachment":[{"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=2328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=2328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/afan.fr\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=2328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}